{"id":1873,"count":1,"description":"","link":"https:\/\/keemanxp.com\/blog\/tag\/samsung-galaxy-s-upgrade","name":"Samsung Galaxy S upgrade","slug":"samsung-galaxy-s-upgrade","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/keemanxp.com\/blog\/wp-json\/wp\/v2\/tags\/1873","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/keemanxp.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/keemanxp.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/keemanxp.com\/blog\/wp-json\/wp\/v2\/posts?tags=1873"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}