{"id":1125,"count":2,"description":"","link":"https:\/\/keemanxp.com\/blog\/tag\/released-date","name":"released date","slug":"released-date","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/keemanxp.com\/blog\/wp-json\/wp\/v2\/tags\/1125","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/keemanxp.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/keemanxp.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/keemanxp.com\/blog\/wp-json\/wp\/v2\/posts?tags=1125"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}